{"id":2696,"date":"2025-12-16T10:07:53","date_gmt":"2025-12-16T15:07:53","guid":{"rendered":"https:\/\/asbtalents.com\/?p=2696"},"modified":"2025-12-16T10:07:54","modified_gmt":"2025-12-16T15:07:54","slug":"un-beau-chaos-pour-le-reveillon","status":"publish","type":"post","link":"https:\/\/asbtalents.com\/en\/un-beau-chaos-pour-le-reveillon\/","title":{"rendered":"Un\u00a0beau chaos\u00a0pour le r\u00e9veillon"},"content":{"rendered":"<p>Un article de V\u00e9ronique Larocque pour <a href=\"https:\/\/www.lapresse.ca\/arts\/television\/2025-12-15\/tele-des-fetes\/classiques-et-nouveautes-a-voir-en-famille.php\">La Presse<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"955\" height=\"662\" src=\"https:\/\/asbtalents.com\/wp-content\/uploads\/2025\/12\/Capture-decran-2025-12-16-100327.png\" alt=\"\" class=\"wp-image-2697\" srcset=\"https:\/\/asbtalents.com\/wp-content\/uploads\/2025\/12\/Capture-decran-2025-12-16-100327.png 955w, https:\/\/asbtalents.com\/wp-content\/uploads\/2025\/12\/Capture-decran-2025-12-16-100327-300x208.png 300w, https:\/\/asbtalents.com\/wp-content\/uploads\/2025\/12\/Capture-decran-2025-12-16-100327-768x532.png 768w, https:\/\/asbtalents.com\/wp-content\/uploads\/2025\/12\/Capture-decran-2025-12-16-100327-18x12.png 18w\" sizes=\"auto, (max-width: 955px) 100vw, 955px\" \/><\/figure>\n\n\n\n<p>Votre temps des F\u00eates ne sera pas de tout repos&nbsp;? Consolez-vous en regardant les vacances rocambolesques des Tremblay-Quersain dans&nbsp;<em>Le beau chaos<\/em>. Les six courts \u00e9pisodes de la saison&nbsp;2 renouent avec cette famille recompos\u00e9e incapable de passer un No\u00ebl sans emb\u00fbches. Au lieu de s\u2019envoler pour Cayo Coco comme pr\u00e9vu, le clan se retrouve dans un chalet \u00ab&nbsp;parfaitement creepy&nbsp;\u00bb au Lac-du-Rang-des-Rennes. Audrey Roger, Tom Gohier, L\u00e9o Mai, Catherine Proulx-Lemay, Martin-David Peters et Mich\u00e8le Deslauriers donnent vie \u00e0 cette dr\u00f4le de famille.<\/p>\n\n\n\n<p>Sur les plateformes de T\u00e9l\u00e9-Qu\u00e9bec<\/p>\n\n\n\n<p><a href=\"https:\/\/video.telequebec.tv\/details\/52435\">Visionnez les \u00e9pisodes<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Un article de V\u00e9ronique Larocque pour La Presse Votre temps des F\u00eates ne sera pas de tout repos&nbsp;? Consolez-vous en regardant les vacances rocambolesques des Tremblay-Quersain dans&nbsp;Le beau chaos. Les six courts \u00e9pisodes de la saison&nbsp;2 renouent avec cette famille recompos\u00e9e incapable de passer un No\u00ebl sans emb\u00fbches. Au lieu de s\u2019envoler pour Cayo Coco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2698,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/posts\/2696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/comments?post=2696"}],"version-history":[{"count":1,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/posts\/2696\/revisions"}],"predecessor-version":[{"id":2699,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/posts\/2696\/revisions\/2699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/media\/2698"}],"wp:attachment":[{"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/media?parent=2696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/categories?post=2696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asbtalents.com\/en\/wp-json\/wp\/v2\/tags?post=2696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}